{"id":6545,"date":"2018-02-28T12:11:21","date_gmt":"2018-02-28T11:11:21","guid":{"rendered":"http:\/\/www.arbaletriers.be\/wordpress\/wp-content\/uploads\/2018\/02\/Couv_Page_1.jpeg"},"modified":"2018-02-28T12:11:21","modified_gmt":"2018-02-28T11:11:21","slug":"couv_page_1","status":"inherit","type":"attachment","link":"https:\/\/www.arbaletriers.be\/wordpress\/le-balestrin-02\/couv_page_1\/","title":{"rendered":"Couv_Page_1"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-6545","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.arbaletriers.be\/wordpress\/wp-content\/uploads\/2018\/02\/Couv_Page_1.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/www.arbaletriers.be\/wordpress\/wp-content\/uploads\/2018\/02\/Couv_Page_1-212x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.arbaletriers.be\/wordpress\/wp-content\/uploads\/2018\/02\/Couv_Page_1-212x300.jpeg 212w, https:\/\/www.arbaletriers.be\/wordpress\/wp-content\/uploads\/2018\/02\/Couv_Page_1.jpeg 596w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/><\/a><\/p>\n<div id=\"themify_builder_content-6545\" data-postid=\"6545\" class=\"themify_builder_content themify_builder_content-6545 themify_builder themify_builder_front\">\n\t<\/div>\n<!-- \/themify_builder_content -->"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":596,"height":842,"file":"2018\/02\/Couv_Page_1.jpeg","sizes":{"thumbnail":{"file":"Couv_Page_1-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.arbaletriers.be\/wordpress\/wp-content\/uploads\/2018\/02\/Couv_Page_1-150x150.jpeg"},"medium":{"file":"Couv_Page_1-212x300.jpeg","width":212,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.arbaletriers.be\/wordpress\/wp-content\/uploads\/2018\/02\/Couv_Page_1-212x300.jpeg"},"full":{"file":"Couv_Page_1.jpeg","width":596,"height":842,"mime_type":"image\/jpeg","source_url":"https:\/\/www.arbaletriers.be\/wordpress\/wp-content\/uploads\/2018\/02\/Couv_Page_1.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[],"resized_images":["350x500","998x500","326x326","300x150","200x100","400x200","760x300","600x350","600x300","998x1409"]}},"post":6544,"source_url":"https:\/\/www.arbaletriers.be\/wordpress\/wp-content\/uploads\/2018\/02\/Couv_Page_1.jpeg","_links":{"self":[{"href":"https:\/\/www.arbaletriers.be\/wordpress\/wp-json\/wp\/v2\/media\/6545"}],"collection":[{"href":"https:\/\/www.arbaletriers.be\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.arbaletriers.be\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.arbaletriers.be\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arbaletriers.be\/wordpress\/wp-json\/wp\/v2\/comments?post=6545"}]}}